{"id":57,"date":"2023-11-07T14:13:56","date_gmt":"2023-11-07T13:13:56","guid":{"rendered":"https:\/\/main.sitrading.com\/?p=57"},"modified":"2024-01-31T11:05:03","modified_gmt":"2024-01-31T10:05:03","slug":"wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen","status":"publish","type":"post","link":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/","title":{"rendered":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen"},"content":{"rendered":"\n<p id=\"viewer-foo\"><em>Der Absatz von Elektronikprodukten w\u00e4chst stetig. Deshalb sind klimafreundliche Ans\u00e4tze wichtiger denn je. Einem deutschen Start-up k\u00f6nnte jetzt der entscheidende Durchbruch gelungen sein \u2013 mit innovativen Technologien, die den CO2-Fu\u00dfabdruck von Leiterplatten drastisch reduzieren.<\/em><\/p>\n\n\n\n<p id=\"viewer-3786c\">Leiterplatten sind das Herzst\u00fcck vieler elektronischer Ger\u00e4te \u2013 und ein oft \u00fcbersehener Umweltverschmutzer, denn die Elektronikindustrie ist bekanntlich schnelllebig. Seit Jahren w\u00e4chst das Bewusstsein f\u00fcr gr\u00fcne Alternativen, doch wirtschaftlich sinnvolle L\u00f6sungen sind noch selten. Das deutsche Start-up Jiva Materials k\u00f6nnte jetzt die Wende bringen: Mit Soluboard hat es eine Leiterplatte entwickelt, die den CO2-Fu\u00dfabdruck im Vergleich zu herk\u00f6mmlichen Produkten um beeindruckende 60 Prozent reduzieren k\u00f6nnte. Pro Quadratmeter Leiterplatte sollen 10,5 kg Kohlenstoff und 620 g Kunststoff eingespart werden.<\/p>\n\n\n\n<p id=\"viewer-8gi07\">Herk\u00f6mmliche Leiterplatten bestehen aus Glasfasern und Harz \u2013 Materialien, die nicht nur energieintensiv in der Herstellung, sondern auch problematisch bei der Entsorgung sind. Soluboard hingegen besteht aus Naturfasern und einem speziellen Polymer, das in hei\u00dfem Wasser l\u00f6slich ist. Das er\u00f6ffnet v\u00f6llig neue M\u00f6glichkeiten f\u00fcr das Recycling und reduziert die Umweltbelastung erheblich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Durchbruch in der Leiterplattentechnologie<\/h2>\n\n\n\n<p id=\"viewer-45ua2\">Gro\u00dfe Namen der Elektronikindustrie haben das Potenzial bereits erkannt. Infineon Technologies, ein f\u00fchrender Halbleiterhersteller, hat Soluboard in seine Produktpalette aufgenommen. Laut Andreas Kopp, Head of Product Management Discretes bei Infineon, bietet Soluboard sowohl \u00f6kologische als auch \u00f6konomische <a href=\"https:\/\/www.infineon.com\/cms\/en\/about-infineon\/press\/market-news\/2023\/INFGIP202307-137.html\" target=\"_blank\" rel=\"noreferrer noopener\">Vorteile<\/a>. Jonathan Swanston, CEO und Mitbegr\u00fcnder von Jiva Materials, sieht in seinem Produkt nicht nur einen Schritt in Richtung Umweltschutz, sondern auch eine Chance f\u00fcr Unternehmen, wertvolle Metalle effektiver zur\u00fcckzugewinnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nachhaltigkeit durch Innovation<\/h3>\n\n\n\n<p id=\"viewer-71hqt\">Die Elektronikindustrie steht vor einer entscheidenden Weggabelung. Mit der steigenden Nachfrage nach Technologien wie etwa Halbleitern r\u00fcckt auch deren Umweltvertr\u00e4glichkeit immer mehr in den Fokus. Soluboard k\u00f6nnte der Auftakt f\u00fcr eine Reihe von Entwicklungen sein, bei denen die Effekte auf das Klima st\u00e4rker ber\u00fccksichtigt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.<\/p>\n","protected":false},"author":1,"featured_media":25,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-57","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-si-electronics"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"tc_admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SI Group - Excellence in Operations\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group\" \/>\n\t\t<meta property=\"og:description\" content=\"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-07T13:13:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-31T10:05:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#blogposting\",\"name\":\"Wasserl\\u00f6sliche Leiterplatten: Die gr\\u00fcne Technologie von morgen - SI Group\",\"headline\":\"Wasserl\\u00f6sliche Leiterplatten: Die gr\\u00fcne Technologie von morgen\",\"author\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/si-group.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/56def8_7091618e55ea4fc9bd46e1febf468b4amv2.webp\",\"width\":740,\"height\":463},\"datePublished\":\"2023-11-07T14:13:56+01:00\",\"dateModified\":\"2024-01-31T11:05:03+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#webpage\"},\"articleSection\":\"SI Electronics, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/si-group.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/#listItem\",\"name\":\"SI Electronics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/#listItem\",\"position\":2,\"name\":\"SI Electronics\",\"item\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#listItem\",\"name\":\"Wasserl\\u00f6sliche Leiterplatten: Die gr\\u00fcne Technologie von morgen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#listItem\",\"position\":3,\"name\":\"Wasserl\\u00f6sliche Leiterplatten: Die gr\\u00fcne Technologie von morgen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/#listItem\",\"name\":\"SI Electronics\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#organization\",\"name\":\"main.sitrading.com\",\"description\":\"Excellence in Operations\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/\",\"name\":\"tc_admin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#webpage\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/\",\"name\":\"Wasserl\\u00f6sliche Leiterplatten: Die gr\\u00fcne Technologie von morgen - SI Group\",\"description\":\"Ein deutsches Start-up ebnet den Weg f\\u00fcr eine nachhaltigere Elektronikindustrie.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/si-group.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/56def8_7091618e55ea4fc9bd46e1febf468b4amv2.webp\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#mainImage\",\"width\":740,\"height\":463},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\\\/#mainImage\"},\"datePublished\":\"2023-11-07T14:13:56+01:00\",\"dateModified\":\"2024-01-31T11:05:03+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/\",\"name\":\"main.sitrading.com\",\"description\":\"Excellence in Operations\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group","description":"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.","canonical_url":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#blogposting","name":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group","headline":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen","author":{"@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author"},"publisher":{"@id":"https:\/\/si-group.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/si-group.com\/wp-content\/uploads\/2023\/11\/56def8_7091618e55ea4fc9bd46e1febf468b4amv2.webp","width":740,"height":463},"datePublished":"2023-11-07T14:13:56+01:00","dateModified":"2024-01-31T11:05:03+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#webpage"},"isPartOf":{"@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#webpage"},"articleSection":"SI Electronics, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/si-group.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/category\/si-electronics\/#listItem","name":"SI Electronics"}},{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/category\/si-electronics\/#listItem","position":2,"name":"SI Electronics","item":"https:\/\/si-group.com\/de\/category\/si-electronics\/","nextItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#listItem","name":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#listItem","position":3,"name":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen","previousItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/category\/si-electronics\/#listItem","name":"SI Electronics"}}]},{"@type":"Organization","@id":"https:\/\/si-group.com\/de\/#organization","name":"main.sitrading.com","description":"Excellence in Operations","url":"https:\/\/si-group.com\/de\/"},{"@type":"Person","@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author","url":"https:\/\/si-group.com\/de\/author\/tc_admin\/","name":"tc_admin"},{"@type":"WebPage","@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#webpage","url":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/","name":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group","description":"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/si-group.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#breadcrumblist"},"author":{"@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author"},"creator":{"@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/si-group.com\/wp-content\/uploads\/2023\/11\/56def8_7091618e55ea4fc9bd46e1febf468b4amv2.webp","@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#mainImage","width":740,"height":463},"primaryImageOfPage":{"@id":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/#mainImage"},"datePublished":"2023-11-07T14:13:56+01:00","dateModified":"2024-01-31T11:05:03+01:00"},{"@type":"WebSite","@id":"https:\/\/si-group.com\/de\/#website","url":"https:\/\/si-group.com\/de\/","name":"main.sitrading.com","description":"Excellence in Operations","inLanguage":"de-DE","publisher":{"@id":"https:\/\/si-group.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"SI Group - Excellence in Operations","og:type":"article","og:title":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group","og:description":"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie.","og:url":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/","article:published_time":"2023-11-07T13:13:56+00:00","article:modified_time":"2024-01-31T10:05:03+00:00","twitter:card":"summary_large_image","twitter:title":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen - SI Group","twitter:description":"Ein deutsches Start-up ebnet den Weg f\u00fcr eine nachhaltigere Elektronikindustrie."},"aioseo_meta_data":{"post_id":"57","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-16 13:13:57","updated":"2025-07-10 15:15:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/si-group.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/si-group.com\/de\/category\/si-electronics\/\" title=\"SI Electronics\">SI Electronics<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/si-group.com\/de\/"},{"label":"SI Electronics","link":"https:\/\/si-group.com\/de\/category\/si-electronics\/"},{"label":"Wasserl\u00f6sliche Leiterplatten: Die gr\u00fcne Technologie von morgen","link":"https:\/\/si-group.com\/de\/wasserloesliche-leiterplatten-die-gruene-technologie-von-morgen\/"}],"acf":[],"_links":{"self":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":2,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"predecessor-version":[{"id":484,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts\/57\/revisions\/484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/media\/25"}],"wp:attachment":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}