{"id":386,"date":"2023-12-13T16:20:07","date_gmt":"2023-12-13T15:20:07","guid":{"rendered":"https:\/\/main.sitrading.com\/?p=386"},"modified":"2023-12-13T16:20:50","modified_gmt":"2023-12-13T15:20:50","slug":"chip-krise-warum-das-dritte-quartal-die-wende-brachte","status":"publish","type":"post","link":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/","title":{"rendered":"Chip-Krise: Warum das dritte Quartal die Wende brachte"},"content":{"rendered":"\n<p id=\"viewer-37kdh\"><em>Nach Jahren der Herausforderungen erreicht die Halbleiterindustrie in Q3 2023 einen Wendepunkt. Positive Signale aus verschiedenen Marktsegmenten und ein Boost durch den neuen iPhone-Produktionszyklus st\u00e4rken die Widerstandsf\u00e4higkeit der Branche gegen\u00fcber globalen Marktst\u00fcrmen.<\/em><\/p>\n\n\n\n<p id=\"viewer-1ruod\">Die Halbleiterindustrie hat in den letzten Jahren viele H\u00f6hen und Tiefen erlebt. Nun zeichnet sich eine positive Wende ab: Laut <a href=\"https:\/\/semi.org\/en\/news-media-press-releases\/semi-press-releases\/global-semiconductor-industry-on-track-for-2024-recovery-but-near-term-headwinds-remain-semi-reports\" target=\"_blank\" rel=\"noreferrer noopener\">SEMI und TechInsights<\/a> sind die IC-Ums\u00e4tze im dritten Quartal 2023 deutlich gestiegen. Insbesondere die Nachfrage nach leistungsstarken Chips und die Produktion des neuen iPhones befl\u00fcgeln die Branche. Der Elektronikmarkt verzeichnet ein gesundes Quartalswachstum von 10 Prozent.<\/p>\n\n\n\n<p id=\"viewer-3e0kf\">Dies ist jedoch nicht auf eine h\u00f6here Nachfrage nach Kernprodukten wie Smartphones, PCs und Notebooks zur\u00fcckzuf\u00fchren. Im September sprach <a href=\"https:\/\/www.trendforce.com\/presscenter\/news\/20230905-11827.html\" target=\"_blank\" rel=\"noreferrer noopener\">Trendforce<\/a> davon, dass diese Nachfrage im dritten Quartal sogar sinken und zu einer geringeren Auslastung der Fertigungsprozesse f\u00fchren werde. Die Erholung beruhe vielmehr auf einer besseren Anpassung von Angebot und Nachfrage, die in der ersten Jahresh\u00e4lfte 2023 stark verschoben waren.<\/p>\n\n\n\n<p id=\"viewer-am21u\">Damals hatte die weltweite Verknappung von Chips eine Zunahme von Eilauftr\u00e4gen forciert. Die Halbleiterhersteller haben daraufhin ihre Kapazit\u00e4ten erh\u00f6ht, um die steigende Nachfrage aus verschiedenen Marktsegmenten wie Industrie, Kommunikation und Unterhaltungselektronik zu befriedigen. Die Folge war ein \u00dcberangebot an bestimmten Chips, wodurch die Preise und die Kapazit\u00e4tsauslastung unter Druck gerieten.<\/p>\n\n\n\n<p id=\"viewer-ccjgc\">Im dritten Quartal 2023 waren die Halbleiterhersteller nun in der Lage, ihre Produktion besser an die tats\u00e4chliche Nachfrage anzupassen und dadurch ihre Ums\u00e4tze zu steigern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impulse durch neues iPhone und 3nm-Prozess<\/h2>\n\n\n\n<p id=\"viewer-b1j1k\">Die Taiwan Semiconductor Manufacturing Company Limited (TSMC) erwartet eine steigende Nachfrage nach Komponenten, angetrieben durch den neuen iPhone-Produktionszyklus. Dar\u00fcber hinaus k\u00f6nnte die Einf\u00fchrung des 3-Nanometer-Prozesses (3 nm) f\u00fcr Aufwind sorgen. Gemeint ist damit eine neue Generation von Silizium-Halbleiterchips mit h\u00f6herer Transistordichte, mehr Geschwindigkeit und weniger Stromverbrauch.<\/p>\n\n\n\n<p id=\"viewer-cbvh8\">Andere Akteure wie ASML und Nexchip senden ebenfalls positive Signale. ASML verzeichnete im dritten Quartal 2023 einen Nettoumsatz von 6,7 Milliarden Euro und einen Nettogewinn von 1,9 Milliarden Euro. Nexchip konnte dank der gestiegenen Nachfrage nach LDDI- und TDDI-Bauteilen seinen Platz unter den Top Ten der Halbleiterhersteller zur\u00fcckerobern. <\/p>\n\n\n\n<p id=\"viewer-cbvh8\">Die Zeichen stehen also gut, dass die Halbleiterindustrie die Talsohle durchschritten hat und sich auf dem Weg der Erholung befindet. Die h\u00f6here Nachfrage und neue Technologiezyklen k\u00f6nnten im vierten Quartal weitere Wachstumschancen bringen.<\/p>\n\n\n\n<div id=\"quoteblock_7046be07f9d87d759843c2e144cb2424\" class=\"block__quote -detect-in-viewport\">\n\n    <div class=\"block__quote__wrapper \">\n\n                    <div class=\"block__quote__quote\">\n                Erholung und Aufschwung: Die Halbleiterindustrie befindet sich im Aufw\u00e4rtstrend.            <\/div>\n        \n        \n        \n    <\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.<\/p>\n","protected":false},"author":1,"featured_media":389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-si-electronics"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"tc_admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SI Group - Excellence in Operations\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group\" \/>\n\t\t<meta property=\"og:description\" content=\"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-13T15:20:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-13T15:20:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#blogposting\",\"name\":\"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group\",\"headline\":\"Chip-Krise: Warum das dritte Quartal die Wende brachte\",\"author\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/si-group.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/56def8_5a41b2596fa4457da4c5ca40ed58f5ebmv2.webp\",\"width\":2069,\"height\":1435,\"caption\":\"Halbleitermarkt: Auf Erholungskurs\"},\"datePublished\":\"2023-12-13T16:20:07+01:00\",\"dateModified\":\"2023-12-13T16:20:50+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#webpage\"},\"articleSection\":\"SI Electronics, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/si-group.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/#listItem\",\"name\":\"SI Electronics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/#listItem\",\"position\":2,\"name\":\"SI Electronics\",\"item\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#listItem\",\"name\":\"Chip-Krise: Warum das dritte Quartal die Wende brachte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#listItem\",\"position\":3,\"name\":\"Chip-Krise: Warum das dritte Quartal die Wende brachte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/category\\\/si-electronics\\\/#listItem\",\"name\":\"SI Electronics\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#organization\",\"name\":\"main.sitrading.com\",\"description\":\"Excellence in Operations\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/\",\"name\":\"tc_admin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#webpage\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/\",\"name\":\"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group\",\"description\":\"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\\u00f6glichkeiten er\\u00f6ffnet.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/author\\\/tc_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/si-group.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/56def8_5a41b2596fa4457da4c5ca40ed58f5ebmv2.webp\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#mainImage\",\"width\":2069,\"height\":1435,\"caption\":\"Halbleitermarkt: Auf Erholungskurs\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\\\/#mainImage\"},\"datePublished\":\"2023-12-13T16:20:07+01:00\",\"dateModified\":\"2023-12-13T16:20:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/si-group.com\\\/de\\\/\",\"name\":\"main.sitrading.com\",\"description\":\"Excellence in Operations\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/si-group.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group","description":"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.","canonical_url":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#blogposting","name":"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group","headline":"Chip-Krise: Warum das dritte Quartal die Wende brachte","author":{"@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author"},"publisher":{"@id":"https:\/\/si-group.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/si-group.com\/wp-content\/uploads\/2023\/12\/56def8_5a41b2596fa4457da4c5ca40ed58f5ebmv2.webp","width":2069,"height":1435,"caption":"Halbleitermarkt: Auf Erholungskurs"},"datePublished":"2023-12-13T16:20:07+01:00","dateModified":"2023-12-13T16:20:50+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#webpage"},"isPartOf":{"@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#webpage"},"articleSection":"SI Electronics, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/si-group.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/category\/si-electronics\/#listItem","name":"SI Electronics"}},{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/category\/si-electronics\/#listItem","position":2,"name":"SI Electronics","item":"https:\/\/si-group.com\/de\/category\/si-electronics\/","nextItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#listItem","name":"Chip-Krise: Warum das dritte Quartal die Wende brachte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#listItem","position":3,"name":"Chip-Krise: Warum das dritte Quartal die Wende brachte","previousItem":{"@type":"ListItem","@id":"https:\/\/si-group.com\/de\/category\/si-electronics\/#listItem","name":"SI Electronics"}}]},{"@type":"Organization","@id":"https:\/\/si-group.com\/de\/#organization","name":"main.sitrading.com","description":"Excellence in Operations","url":"https:\/\/si-group.com\/de\/"},{"@type":"Person","@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author","url":"https:\/\/si-group.com\/de\/author\/tc_admin\/","name":"tc_admin"},{"@type":"WebPage","@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#webpage","url":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/","name":"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group","description":"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/si-group.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#breadcrumblist"},"author":{"@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author"},"creator":{"@id":"https:\/\/si-group.com\/de\/author\/tc_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/si-group.com\/wp-content\/uploads\/2023\/12\/56def8_5a41b2596fa4457da4c5ca40ed58f5ebmv2.webp","@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#mainImage","width":2069,"height":1435,"caption":"Halbleitermarkt: Auf Erholungskurs"},"primaryImageOfPage":{"@id":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/#mainImage"},"datePublished":"2023-12-13T16:20:07+01:00","dateModified":"2023-12-13T16:20:50+01:00"},{"@type":"WebSite","@id":"https:\/\/si-group.com\/de\/#website","url":"https:\/\/si-group.com\/de\/","name":"main.sitrading.com","description":"Excellence in Operations","inLanguage":"de-DE","publisher":{"@id":"https:\/\/si-group.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"SI Group - Excellence in Operations","og:type":"article","og:title":"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group","og:description":"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet.","og:url":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/","article:published_time":"2023-12-13T15:20:07+00:00","article:modified_time":"2023-12-13T15:20:50+00:00","twitter:card":"summary_large_image","twitter:title":"Chip-Krise: Warum das dritte Quartal die Wende brachte - SI Group","twitter:description":"Von der Chip-Knappheit zur Produktionserholung: Das dritte Quartal 2023 hat der Halbleiterindustrie neue Perspektiven und M\u00f6glichkeiten er\u00f6ffnet."},"aioseo_meta_data":{"post_id":"386","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-13 15:11:08","updated":"2025-07-10 15:15:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/si-group.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/si-group.com\/de\/category\/si-electronics\/\" title=\"SI Electronics\">SI Electronics<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tChip-Krise: Warum das dritte Quartal die Wende brachte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/si-group.com\/de\/"},{"label":"SI Electronics","link":"https:\/\/si-group.com\/de\/category\/si-electronics\/"},{"label":"Chip-Krise: Warum das dritte Quartal die Wende brachte","link":"https:\/\/si-group.com\/de\/chip-krise-warum-das-dritte-quartal-die-wende-brachte\/"}],"acf":[],"_links":{"self":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts\/386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/comments?post=386"}],"version-history":[{"count":3,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts\/386\/revisions"}],"predecessor-version":[{"id":397,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/posts\/386\/revisions\/397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/media\/389"}],"wp:attachment":[{"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/media?parent=386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/categories?post=386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/si-group.com\/de\/wp-json\/wp\/v2\/tags?post=386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}